{"id":4870,"date":"2025-08-28T07:35:36","date_gmt":"2025-08-28T07:35:36","guid":{"rendered":"https:\/\/hashivah.org\/?p=4870"},"modified":"2025-08-28T07:54:19","modified_gmt":"2025-08-28T07:54:19","slug":"newspapers-lie","status":"publish","type":"post","link":"https:\/\/hashivah.org\/de\/newspapers-lie\/","title":{"rendered":"\u201eZeitungen l\u00fcgen\u201c"},"content":{"rendered":"<p><strong>Die Hamas stiehlt Lebensmittellieferungen in Gaza<\/strong><br \/>\n<span style=\"color: #ffffff;\">_<\/span><\/p>\n<p><strong><span class=\"dropcap dropcap3\">\u201eZ<\/span>eitungen l\u00fcgen.\u201c Das waren die Worte meines Gro\u00dfvaters Shaul Nissan Goldberg. Die Nazis ermordeten ihn vor 86 Jahren, aber er h\u00e4tte heute noch mehr Recht, denn seine Worte gelten nicht nur f\u00fcr Zeitungen.<\/strong><\/p>\n<p>\u00b7 Bilder von abgemagerten Kindern, die an genetischen Krankheiten leiden, werden f\u00e4lschlicherweise als \u201ehungernde Kinder in Gaza\u201c bezeichnet, w\u00e4hrend ihre anwesenden Pfleger wohlgen\u00e4hrt aussehen. Dies entwertet die Integrit\u00e4t von Journalisten zu einem Propagandaarm sch\u00e4ndlicher Terroristen. Die BBC weist ihre Reporter an, das Leid in Gaza hervorzuheben und zu sagen, dass Israels Hilfsplan \u201enicht funktioniert\u201c, unabh\u00e4ngig davon, wie viele Hilfsg\u00fcter geliefert werden.<\/p>\n<p>\u00b7 Hilfsorganisationen mit mehreren Millionen Dollar lassen ihre Vorr\u00e4te in Gaza verrotten, weil sie sich weigern, die Auslieferung mit Israel zu koordinieren. Die Organisationen kooperieren mit der <em>Hamas<\/em> (d. h. sie erpressen), um die Lieferungen durchzubekommen. Die Bestechungsgelder in Form von G\u00fctern f\u00fcr die Hamas werden dann zu Wucherpreisen weiterverkauft. Pastor Johnnie Moore vom <em>Gaza Humanitarian Fund,<\/em> der einzigen Gruppe, die <em>mit<\/em> Israel zusammenarbeitet, gibt an, dass 100 Millionen Lebensmittelpakete <em>gratis<\/em> geliefert wurden, genug, um ganz Gaza 2 Monate lang zu versorgen. Die Leugnung durch UN und Sprecher von Hilfsorganisationen sind reine L\u00fcgenm\u00e4rchen.<\/p>\n<p>\u00b7 Todeszahlen des Gesundheitsministeriums in Gaza (korrekterweise des Propagandaministeriums der Hamas) werden als reine Wahrheit akzeptiert. Die erfundenen Zahlen sind unbest\u00e4tigt, da sie es nicht sein k\u00f6nnen. Die Hamas bl\u00e4ht die Zahlen auf, da mehr Todesf\u00e4lle zu mehr weltweitem Mitgef\u00fchl f\u00fchren. Die wichtigste Waffe der Hamas ist die Ausbeutung von Kindern, seien es hungrige Kinder aus Gaza oder, oft missbrauchte Bilder von kranken Kindern in Afghanistan, Syrien oder im Jemen.<\/p>\n<p>\u00b7 Es wurden Bilder von einem brennenden Feld neben einer Kirche ver\u00f6ffentlicht. Israelische Jugendliche versuchten, die von Arabern gelegten Feuer zu l\u00f6schen. Die Medien beschuldigten Israel jedoch, Kirchen niedergebrannt zu haben.<\/p>\n<p>\u00b7 Schreckliche Massaker an Drusen in Syrien, wie die Ermordung von Juden am 7. Oktober, veranlassten Israel, sie vor den angreifenden Islamisten zu retten. Die Welt verurteilte Israel f\u00fcr seine \u201eInvasion\u201c.<\/p>\n<p>\u00b7 Die Staatsoberh\u00e4upter Frankreichs, Gro\u00dfbritanniens und Kanadas verb\u00fcnden die Anerkennung Pal\u00e4stinas, einer nie zuvor existierenden Einheit, und belohnen damit barbarischen Terror. Die Hamas erkl\u00e4rte den Sieg und erh\u00f6hte sofort ihre Forderungen, wodurch der Krieg erneut verl\u00e4ngert wird.<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Hamas stiehlt Lebensmittellieferungen in Gaza _ \u201eZeitungen l\u00fcgen.\u201c Das waren die Worte meines Gro\u00dfvaters Shaul Nissan Goldberg. Die Nazis ermordeten ihn vor 86 Jahren, aber er h\u00e4tte heute noch mehr Recht, denn seine Worte gelten nicht nur f\u00fcr Zeitungen. \u00b7 Bilder von abgemagerten Kindern, die an genetischen Krankheiten leiden, werden f\u00e4lschlicherweise als \u201ehungernde Kinder [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":4871,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5,33],"tags":[],"class_list":["post-4870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","category-featured"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201eZeitungen l\u00fcgen\u201c - Lema&#039;an Zion<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hashivah.org\/newspapers-lie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201eZeitungen l\u00fcgen\u201c - Lema&#039;an Zion\" \/>\n<meta property=\"og:description\" content=\"Die Hamas stiehlt Lebensmittellieferungen in Gaza _ \u201eZeitungen l\u00fcgen.\u201c Das waren die Worte meines Gro\u00dfvaters Shaul Nissan Goldberg. Die Nazis ermordeten ihn vor 86 Jahren, aber er h\u00e4tte heute noch mehr Recht, denn seine Worte gelten nicht nur f\u00fcr Zeitungen. \u00b7 Bilder von abgemagerten Kindern, die an genetischen Krankheiten leiden, werden f\u00e4lschlicherweise als \u201ehungernde Kinder [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hashivah.org\/newspapers-lie\/\" \/>\n<meta property=\"og:site_name\" content=\"Lema&#039;an Zion\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-28T07:35:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-28T07:54:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hashivah.org\/wp-content\/uploads\/2025\/08\/Hamas-steals-food-supply-in-Gaza.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"David B. Goldberg, M.A.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"David B. Goldberg, M.A.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hashivah.org\/newspapers-lie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hashivah.org\/newspapers-lie\/\"},\"author\":{\"name\":\"David B. Goldberg, M.A.\",\"@id\":\"https:\/\/hashivah.org\/#\/schema\/person\/2bddd9ada511fa73843ae58b5e797eaa\"},\"headline\":\"\u201eZeitungen l\u00fcgen\u201c\",\"datePublished\":\"2025-08-28T07:35:36+00:00\",\"dateModified\":\"2025-08-28T07:54:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hashivah.org\/newspapers-lie\/\"},\"wordCount\":1116,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/hashivah.org\/newspapers-lie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hashivah.org\/wp-content\/uploads\/2025\/08\/Hamas-steals-food-supply-in-Gaza.png\",\"articleSection\":[\"Artikel\",\"Featured\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hashivah.org\/newspapers-lie\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hashivah.org\/newspapers-lie\/\",\"url\":\"https:\/\/hashivah.org\/newspapers-lie\/\",\"name\":\"\u201eZeitungen l\u00fcgen\u201c - Lema&#039;an Zion\",\"isPartOf\":{\"@id\":\"https:\/\/hashivah.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hashivah.org\/newspapers-lie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hashivah.org\/newspapers-lie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hashivah.org\/wp-content\/uploads\/2025\/08\/Hamas-steals-food-supply-in-Gaza.png\",\"datePublished\":\"2025-08-28T07:35:36+00:00\",\"dateModified\":\"2025-08-28T07:54:19+00:00\",\"author\":{\"@id\":\"https:\/\/hashivah.org\/#\/schema\/person\/2bddd9ada511fa73843ae58b5e797eaa\"},\"breadcrumb\":{\"@id\":\"https:\/\/hashivah.org\/newspapers-lie\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hashivah.org\/newspapers-lie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/hashivah.org\/newspapers-lie\/#primaryimage\",\"url\":\"https:\/\/hashivah.org\/wp-content\/uploads\/2025\/08\/Hamas-steals-food-supply-in-Gaza.png\",\"contentUrl\":\"https:\/\/hashivah.org\/wp-content\/uploads\/2025\/08\/Hamas-steals-food-supply-in-Gaza.png\",\"width\":640,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hashivah.org\/newspapers-lie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hashivah.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cNewspapers lie\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hashivah.org\/#website\",\"url\":\"https:\/\/hashivah.org\/\",\"name\":\"Lema&#039;an Zion\",\"description\":\"My WordPress Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hashivah.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/hashivah.org\/#\/schema\/person\/2bddd9ada511fa73843ae58b5e797eaa\",\"name\":\"David B. Goldberg, M.A.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/hashivah.org\/wp-content\/uploads\/2021\/11\/unnamed-150x150.png\",\"url\":\"https:\/\/hashivah.org\/wp-content\/uploads\/2021\/11\/unnamed-150x150.png\",\"contentUrl\":\"https:\/\/hashivah.org\/wp-content\/uploads\/2021\/11\/unnamed-150x150.png\",\"caption\":\"David B. Goldberg, M.A.\"},\"url\":\"https:\/\/hashivah.org\/de\/author\/dave\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201eZeitungen l\u00fcgen\u201c - Lema&#039;an Zion","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hashivah.org\/newspapers-lie\/","og_locale":"de_DE","og_type":"article","og_title":"\u201eZeitungen l\u00fcgen\u201c - Lema&#039;an Zion","og_description":"Die Hamas stiehlt Lebensmittellieferungen in Gaza _ \u201eZeitungen l\u00fcgen.\u201c Das waren die Worte meines Gro\u00dfvaters Shaul Nissan Goldberg. Die Nazis ermordeten ihn vor 86 Jahren, aber er h\u00e4tte heute noch mehr Recht, denn seine Worte gelten nicht nur f\u00fcr Zeitungen. \u00b7 Bilder von abgemagerten Kindern, die an genetischen Krankheiten leiden, werden f\u00e4lschlicherweise als \u201ehungernde Kinder [&hellip;]","og_url":"https:\/\/hashivah.org\/newspapers-lie\/","og_site_name":"Lema&#039;an Zion","article_published_time":"2025-08-28T07:35:36+00:00","article_modified_time":"2025-08-28T07:54:19+00:00","og_image":[{"width":640,"height":395,"url":"https:\/\/hashivah.org\/wp-content\/uploads\/2025\/08\/Hamas-steals-food-supply-in-Gaza.png","type":"image\/png"}],"author":"David B. Goldberg, M.A.","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"David B. Goldberg, M.A.","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hashivah.org\/newspapers-lie\/#article","isPartOf":{"@id":"https:\/\/hashivah.org\/newspapers-lie\/"},"author":{"name":"David B. Goldberg, M.A.","@id":"https:\/\/hashivah.org\/#\/schema\/person\/2bddd9ada511fa73843ae58b5e797eaa"},"headline":"\u201eZeitungen l\u00fcgen\u201c","datePublished":"2025-08-28T07:35:36+00:00","dateModified":"2025-08-28T07:54:19+00:00","mainEntityOfPage":{"@id":"https:\/\/hashivah.org\/newspapers-lie\/"},"wordCount":1116,"commentCount":0,"image":{"@id":"https:\/\/hashivah.org\/newspapers-lie\/#primaryimage"},"thumbnailUrl":"https:\/\/hashivah.org\/wp-content\/uploads\/2025\/08\/Hamas-steals-food-supply-in-Gaza.png","articleSection":["Artikel","Featured"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hashivah.org\/newspapers-lie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hashivah.org\/newspapers-lie\/","url":"https:\/\/hashivah.org\/newspapers-lie\/","name":"\u201eZeitungen l\u00fcgen\u201c - Lema&#039;an Zion","isPartOf":{"@id":"https:\/\/hashivah.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hashivah.org\/newspapers-lie\/#primaryimage"},"image":{"@id":"https:\/\/hashivah.org\/newspapers-lie\/#primaryimage"},"thumbnailUrl":"https:\/\/hashivah.org\/wp-content\/uploads\/2025\/08\/Hamas-steals-food-supply-in-Gaza.png","datePublished":"2025-08-28T07:35:36+00:00","dateModified":"2025-08-28T07:54:19+00:00","author":{"@id":"https:\/\/hashivah.org\/#\/schema\/person\/2bddd9ada511fa73843ae58b5e797eaa"},"breadcrumb":{"@id":"https:\/\/hashivah.org\/newspapers-lie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hashivah.org\/newspapers-lie\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hashivah.org\/newspapers-lie\/#primaryimage","url":"https:\/\/hashivah.org\/wp-content\/uploads\/2025\/08\/Hamas-steals-food-supply-in-Gaza.png","contentUrl":"https:\/\/hashivah.org\/wp-content\/uploads\/2025\/08\/Hamas-steals-food-supply-in-Gaza.png","width":640,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/hashivah.org\/newspapers-lie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hashivah.org\/"},{"@type":"ListItem","position":2,"name":"\u201cNewspapers lie\u201d"}]},{"@type":"WebSite","@id":"https:\/\/hashivah.org\/#website","url":"https:\/\/hashivah.org\/","name":"Lema&#039;an Zion","description":"My WordPress Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hashivah.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/hashivah.org\/#\/schema\/person\/2bddd9ada511fa73843ae58b5e797eaa","name":"David B. Goldberg, M.A.","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hashivah.org\/wp-content\/uploads\/2021\/11\/unnamed-150x150.png","url":"https:\/\/hashivah.org\/wp-content\/uploads\/2021\/11\/unnamed-150x150.png","contentUrl":"https:\/\/hashivah.org\/wp-content\/uploads\/2021\/11\/unnamed-150x150.png","caption":"David B. Goldberg, M.A."},"url":"https:\/\/hashivah.org\/de\/author\/dave\/"}]}},"jetpack_featured_media_url":"https:\/\/hashivah.org\/wp-content\/uploads\/2025\/08\/Hamas-steals-food-supply-in-Gaza.png","wps_subtitle":"","_links":{"self":[{"href":"https:\/\/hashivah.org\/de\/wp-json\/wp\/v2\/posts\/4870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hashivah.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hashivah.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hashivah.org\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/hashivah.org\/de\/wp-json\/wp\/v2\/comments?post=4870"}],"version-history":[{"count":5,"href":"https:\/\/hashivah.org\/de\/wp-json\/wp\/v2\/posts\/4870\/revisions"}],"predecessor-version":[{"id":4873,"href":"https:\/\/hashivah.org\/de\/wp-json\/wp\/v2\/posts\/4870\/revisions\/4873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hashivah.org\/de\/wp-json\/wp\/v2\/media\/4871"}],"wp:attachment":[{"href":"https:\/\/hashivah.org\/de\/wp-json\/wp\/v2\/media?parent=4870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hashivah.org\/de\/wp-json\/wp\/v2\/categories?post=4870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hashivah.org\/de\/wp-json\/wp\/v2\/tags?post=4870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}